{"id":94237,"date":"2025-07-14T12:39:29","date_gmt":"2025-07-14T10:39:29","guid":{"rendered":"https:\/\/www.limos4.com\/durabilite"},"modified":"2026-07-06T08:20:52","modified_gmt":"2026-07-06T06:20:52","slug":"durabilite","status":"publish","type":"page","link":"https:\/\/www.limos4.com\/fr\/durabilite","title":{"rendered":"Durabilit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"94237\" class=\"elementor elementor-94237 elementor-94096\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d754c6d elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"d754c6d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7c74402 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"7c74402\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b047f43 elementor-widget elementor-widget-text-editor\" data-id=\"b047f43\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t1\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-587f172 elementor-widget elementor-widget-text-editor\" data-id=\"587f172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-472a375\" data-id=\"472a375\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-30d9978 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"30d9978\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-932dafc\" data-id=\"932dafc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1327e82 e-con-full e-flex e-con e-child\" data-id=\"1327e82\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6583ff elementor-widget elementor-widget-heading\" data-id=\"f6583ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9veloppement durable chez Limos4 :\n<br \/>Conduire l'avenir<br \/>De mani\u00e8re responsable<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02d9adc elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"02d9adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"61\" height=\"61\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/07\/list.png\" class=\"attachment-thumbnail size-thumbnail wp-image-94100\" alt=\"Sustainability list\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-832fb62 elementor-widget elementor-widget-text-editor\" data-id=\"832fb62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une approche plus \u00e9cologique du transport terrestre<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7b2934 elementor-widget elementor-widget-text-editor\" data-id=\"b7b2934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Limos4, le d\u00e9veloppement durable est un \u00e9l\u00e9ment fondamental de notre vision de l&#8217;avenir du transport terrestre. Nous am\u00e9liorons continuellement nos op\u00e9rations afin de r\u00e9duire les \u00e9missions, d&#8217;optimiser l&#8217;efficacit\u00e9 et de renforcer la durabilit\u00e9 du transport terrestre avec chauffeur. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08ef441 elementor-widget elementor-widget-text-editor\" data-id=\"08ef441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre cadre de d\u00e9veloppement durable holistique s\u2019aligne sur les meilleures pratiques mondiales, garantissant la conformit\u00e9 aux r\u00e9glementations en constante \u00e9volution et d\u00e9passant les attentes des clients. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d156414 elementor-widget elementor-widget-text-editor\" data-id=\"d156414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En \u00e9largissant sa flotte avec des v\u00e9hicules hybrides et \u00e9lectriques, en fournissant des rapports de durabilit\u00e9 automatis\u00e9s et en s&#8217;engageant \u00e0 atteindre la neutralit\u00e9 carbone d&#8217;ici 2040, Limos4 permet aux entreprises de surveiller, de g\u00e9rer et d&#8217;am\u00e9liorer leurs performances en mati\u00e8re de durabilit\u00e9 des d\u00e9placements, conform\u00e9ment aux strat\u00e9gies ESG et aux exigences de reporting.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d78a524 elementor-align-left elementor-tablet-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"d78a524\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/limos4.com\/wp-content\/documents\/Limos4%20Climate%20Pledge%20Preliminary%20Progress%20Report.pdf\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger le rapport pr\u00e9liminaire sur les progr\u00e8s r\u00e9alis\u00e9s en mati\u00e8re d\u2019engagement climatique 2025-2026<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2767fb elementor-widget elementor-widget-template\" data-id=\"c2767fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"81845\" class=\"elementor elementor-81845 elementor-80788 elementor-80788\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2480cee6 e-flex e-con-boxed e-con e-parent\" data-id=\"2480cee6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1572756f elementor-widget elementor-widget-text-editor\" data-id=\"1572756f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fier membre de :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dce81ca e-flex e-con-boxed e-con e-child\" data-id=\"6dce81ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b384e24 elementor-widget elementor-widget-image\" data-id=\"5b384e24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"76\" height=\"22\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/01\/nla.png\" class=\"attachment-large size-large wp-image-80638\" alt=\"nla\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc73201 elementor-widget elementor-widget-image\" data-id=\"6dc73201\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"74\" height=\"21\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/01\/gcla-1.png\" class=\"attachment-large size-large wp-image-80770\" alt=\"gcla\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a59cf91 elementor-widget elementor-widget-image\" data-id=\"3a59cf91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/01\/tams.png\" class=\"attachment-large size-large wp-image-80643\" alt=\"tams\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94bc49d elementor-widget elementor-widget-image\" data-id=\"94bc49d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"116\" height=\"35\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/GBTA.png\" class=\"attachment-large size-large wp-image-83641\" alt=\"GBTA\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d61ba6d elementor-widget elementor-widget-image\" data-id=\"d61ba6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"35\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/01\/ASTM.png\" class=\"attachment-large size-large wp-image-86539\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f32c66 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"6f32c66\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3154ff3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3154ff3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7818264 show-text-on-hover elementor-invisible\" data-id=\"7818264\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f06a5 text-on-hover-title elementor-widget elementor-widget-text-editor\" data-id=\"62f06a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>V\u00e9hicules hybrides et \u00e9lectriques<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba4364 elementor-widget elementor-widget-text-editor\" data-id=\"3ba4364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Solutions de flotte \u00e0 faibles \u00e9missions dans le monde entier.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fb3711a show-text-on-hover elementor-invisible\" data-id=\"fb3711a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1b540b text-on-hover-title elementor-widget elementor-widget-text-editor\" data-id=\"b1b540b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rapport carbone<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-156094b elementor-widget elementor-widget-text-editor\" data-id=\"156094b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Suivi et informations sur l&#8217;empreinte carbone en temps r\u00e9el pour les clients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c3e1c1a show-text-on-hover elementor-invisible\" data-id=\"c3e1c1a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f68755 text-on-hover-title elementor-widget elementor-widget-text-editor\" data-id=\"6f68755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le signataire de l&#8217;Engagement Climatique<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e3cc5 elementor-widget elementor-widget-text-editor\" data-id=\"84e3cc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Engag\u00e9 \u00e0 atteindre z\u00e9ro \u00e9mission nette d\u2019ici 2040.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c63ef94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c63ef94\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fb86dd\" data-id=\"2fb86dd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7353173 elementor-widget elementor-widget-text-editor\" data-id=\"7353173\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>COMME VU DANS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f93b7b4 e-con-full e-flex e-con e-parent\" data-id=\"f93b7b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-58ad83a e-con-full e-flex e-con e-child\" data-id=\"58ad83a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6524118 elementor-widget elementor-widget-image\" data-id=\"6524118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"26\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/los-angeles-times.svg\" class=\"attachment-full size-full wp-image-95919\" alt=\"Los Angeles Times logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c471e1f hide-tablet elementor-hidden-mobile e-con-full elementor-hidden-mobile_extra e-flex e-con e-child\" data-id=\"c471e1f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a2303 elementor-widget elementor-widget-image\" data-id=\"b9a2303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/Line-90.svg\" class=\"attachment-large size-large wp-image-95920\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a50055b e-con-full e-flex e-con e-child\" data-id=\"a50055b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e59f52 elementor-widget-widescreen__width-initial elementor-widget elementor-widget-image\" data-id=\"8e59f52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"30\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/02\/the-business-travel-magazine-logo.svg\" class=\"attachment-full size-full wp-image-88268\" alt=\"Business Travel Magazine Logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3e9291 hide-tablet elementor-hidden-mobile elementor-hidden-mobile_extra e-con-full e-flex e-con e-child\" data-id=\"a3e9291\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-345c5c3 elementor-widget elementor-widget-image\" data-id=\"345c5c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/Line-90.svg\" class=\"attachment-large size-large wp-image-95920\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6c942c e-con-full e-flex e-con e-child\" data-id=\"f6c942c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88285c9 elementor-widget elementor-widget-image\" data-id=\"88285c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"30\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/Esquire-Singapore-logo.svg\" class=\"attachment-full size-full wp-image-95921\" alt=\"Esquire Singapore logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0470b4f elementor-hidden-mobile e-con-full elementor-hidden-mobile_extra e-flex e-con e-child\" data-id=\"0470b4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-943477c elementor-widget elementor-widget-image\" data-id=\"943477c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"23\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/Line-90.svg\" class=\"attachment-full size-full wp-image-95920\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5531adb e-con-full e-flex e-con e-child\" data-id=\"5531adb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-084d599 elementor-widget elementor-widget-image\" data-id=\"084d599\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"30\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/the-telegraph.svg\" class=\"attachment-full size-full wp-image-95922\" alt=\"The Telegraph logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-642ce67 elementor-hidden-mobile e-con-full elementor-hidden-mobile_extra e-flex e-con e-child\" data-id=\"642ce67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed238e elementor-widget elementor-widget-image\" data-id=\"1ed238e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"23\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/06\/Line-90.svg\" class=\"attachment-full size-full wp-image-95920\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-078952f e-con-full e-flex e-con e-child\" data-id=\"078952f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0882a02 elementor-widget elementor-widget-image\" data-id=\"0882a02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mydigitalpublication.com\/publication\/?i=837418\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"30\" src=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/02\/Chauffeur-driven-logo.png\" class=\"attachment-full size-full wp-image-88507\" alt=\"Chauffeur driven logo\" srcset=\"\/\/www.limos4.com\/wp-content\/uploads\/2025\/02\/Chauffeur-driven-logo.png 153w, \/\/www.limos4.com\/wp-content\/uploads\/2025\/02\/Chauffeur-driven-logo-150x30.png 150w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-998aafd elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"998aafd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c34c738 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"c34c738\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-212e6af elementor-widget elementor-widget-text-editor\" data-id=\"212e6af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b0e53d elementor-widget elementor-widget-text-editor\" data-id=\"0b0e53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c06a4bd\" data-id=\"c06a4bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-05d8499 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"05d8499\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dcc35e3\" data-id=\"dcc35e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f7bdf2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4f7bdf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transition\nvers une flotte plus\ndurable<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77c21dc elementor-hidden-tablet elementor-hidden-phone\" data-id=\"77c21dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8398c57\" data-id=\"8398c57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-360e64a elementor-widget elementor-widget-text-editor\" data-id=\"360e64a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La voie vers un transport durable commence par des v\u00e9hicules adapt\u00e9s. Limos4 privil\u00e9gie les v\u00e9hicules hybrides et \u00e9lectriques sur ses march\u00e9s cl\u00e9s, garantissant ainsi \u00e0 ses clients des \u00e9missions r\u00e9duites sans sacrifier le confort, la s\u00e9curit\u00e9 ou l&#8217;efficacit\u00e9. Limos4 s&#8217;engage \u00e0 :  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f28d55d e-con-full e-flex e-con e-parent\" data-id=\"f28d55d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9be6328 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9be6328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Expansion strat\u00e9gique de la flotte hybride et \u00e9lectrique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb1d3e elementor-widget elementor-widget-text-editor\" data-id=\"9fb1d3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Travailler avec notre r\u00e9seau mondial de fournisseurs pour donner la priorit\u00e9 aux v\u00e9hicules hybrides et \u00e9lectriques dans les endroits o\u00f9 l&#8217;infrastructure soutient la mobilit\u00e9 durable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9eb4100 e-con-full e-flex e-con e-parent\" data-id=\"9eb4100\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6340ed elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b6340ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Efficacit\u00e9 pilot\u00e9e par l'IA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7af271 elementor-widget elementor-widget-text-editor\" data-id=\"a7af271\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9partition intelligente et l&#8217;optimisation des itin\u00e9raires r\u00e9duisent le kilom\u00e9trage inutile et la consommation de carburant dans toutes les cat\u00e9gories de v\u00e9hicules.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad4e54c e-con-full e-flex e-con e-parent\" data-id=\"ad4e54c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac9be4b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ac9be4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Int\u00e9gration continue de la durabilit\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c93533 elementor-widget elementor-widget-text-editor\" data-id=\"9c93533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En partenariat avec des fournisseurs qui adh\u00e8rent \u00e0 nos engagements environnementaux, nous garantissons que nos clients b\u00e9n\u00e9ficient de solutions de transport \u00e0 faibles \u00e9missions dans la mesure du possible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0cf9133 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"0cf9133\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-db316a8 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"db316a8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26c59fe elementor-widget elementor-widget-text-editor\" data-id=\"26c59fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3ad845 elementor-widget elementor-widget-text-editor\" data-id=\"d3ad845\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c1269c6\" data-id=\"c1269c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0751602 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0751602\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4050a10\" data-id=\"4050a10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6024144 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6024144\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"orange\">Champ d'application 1 :<\/span>\n\u00c9missions directes\net d\u00e9chets op\u00e9rationnels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-996ff77 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"996ff77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d92f6a4\" data-id=\"d92f6a4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dddfeb elementor-widget elementor-widget-text-editor\" data-id=\"1dddfeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Limos4 poss\u00e8de et exploite un nombre restreint de v\u00e9hicules et met en \u0153uvre des mesures actives pour minimiser leurs \u00e9missions. Si la majeure partie de notre flotte provient de notre r\u00e9seau mondial de fournisseurs (Scope 3), nos op\u00e9rations directes constituent une r\u00e9f\u00e9rence en mati\u00e8re de d\u00e9veloppement durable en int\u00e9grant des solutions de v\u00e9hicules \u00e0 faibles \u00e9missions et en optimisant l&#8217;efficacit\u00e9 de notre flotte. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cbb51e elementor-widget elementor-widget-text-editor\" data-id=\"5cbb51e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Optimisation de la flotte<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15ad213 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"15ad213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9valuation continue et int\u00e9gration progressive des v\u00e9hicules hybrides et \u00e9lectriques en fonction de la disponibilit\u00e9 du march\u00e9 et des infrastructures.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span style=\"font-weight:bold\">Objectif <\/span>: faire passer 50 % de la flotte d\u00e9tenue par Limos4 \u00e0 l'hybride ou \u00e0 l'\u00e9lectrique d'ici 2028, conform\u00e9ment aux engagements de l'entreprise en mati\u00e8re de d\u00e9veloppement durable.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-025aaf3 elementor-widget elementor-widget-text-editor\" data-id=\"025aaf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Am\u00e9liorations de l&#8217;efficacit\u00e9 des itin\u00e9raires<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f3d179 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f3d179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La r\u00e9partition et l'optimisation des itin\u00e9raires aliment\u00e9es par l'IA r\u00e9duisent les temps d'inactivit\u00e9 et la consommation de carburant de tous les v\u00e9hicules exploit\u00e9s par Limos4.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les informations sur les donn\u00e9es en temps r\u00e9el permettent une allocation intelligente des v\u00e9hicules, minimisant ainsi le kilom\u00e9trage inutile.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08e9178 elementor-widget elementor-widget-text-editor\" data-id=\"08e9178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Feuille de route pour la r\u00e9duction des \u00e9missions<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be99d7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0be99d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mise en \u0153uvre d\u2019une feuille de route structur\u00e9e pour r\u00e9duire les \u00e9missions directes du parc automobile, y compris l\u2019\u00e9valuation continue des technologies \u00e9mergentes des v\u00e9hicules.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Adoption de carburants alternatifs et de solutions de mobilit\u00e9 innovantes lorsque cela est possible.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff6febc elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"ff6febc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c8f481d elementor-hidden-tablet elementor-hidden-phone\" data-id=\"c8f481d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc3a7df elementor-widget elementor-widget-text-editor\" data-id=\"dc3a7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fce47f6 elementor-widget elementor-widget-text-editor\" data-id=\"fce47f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p> <\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-23768a0\" data-id=\"23768a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b8a19d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6b8a19d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-17ac66e\" data-id=\"17ac66e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8625a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ac8625a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"orange\">Champ d'application 2 :<\/span>\n\u00c9missions indirectes\nprovenant de l'\u00e9nergie achet\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7f6cedc elementor-hidden-tablet elementor-hidden-phone\" data-id=\"7f6cedc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-132e33a\" data-id=\"132e33a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ff319 elementor-widget elementor-widget-text-editor\" data-id=\"a5ff319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les \u00e9missions de Scope 2 proviennent de l&#8217;\u00e9lectricit\u00e9, du chauffage et de la climatisation que Limos4 ach\u00e8te pour alimenter ses op\u00e9rations. Bien que ces \u00e9missions se produisent dans les installations de production d&#8217;\u00e9nergie, elles r\u00e9sultent de notre consommation d&#8217;\u00e9nergie. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bd3f47 elementor-widget elementor-widget-text-editor\" data-id=\"2bd3f47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Principales initiatives pour la r\u00e9duction du Scope 2 :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7925af9 e-con-full e-flex e-con e-parent\" data-id=\"7925af9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77abb55 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"77abb55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transition vers l'\u00e9lectricit\u00e9 renouvelable<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ceb7c0 elementor-widget elementor-widget-text-editor\" data-id=\"0ceb7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Approvisionnement en \u00e9nergie 100 % verte aupr\u00e8s de fournisseurs d\u2019\u00e9nergie renouvelable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b197c39 e-con-full e-flex e-con e-parent\" data-id=\"b197c39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1254cf5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1254cf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Installations \u00e9co\u00e9nerg\u00e9tiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8505d64 elementor-widget elementor-widget-text-editor\" data-id=\"8505d64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mise \u00e0 niveau vers des syst\u00e8mes CVC intelligents, un \u00e9clairage LED et une surveillance \u00e9nerg\u00e9tique en temps r\u00e9el pour r\u00e9duire le gaspillage d\u2019\u00e9lectricit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6709ebe e-con-full e-flex e-con e-parent\" data-id=\"6709ebe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5285ef6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5285ef6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Infrastructure num\u00e9rique durable<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df306dd elementor-widget elementor-widget-text-editor\" data-id=\"df306dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Optimiser le stockage cloud, r\u00e9duire le traitement redondant des donn\u00e9es et travailler avec des centres de donn\u00e9es \u00e9cologiques aliment\u00e9s par des \u00e9nergies renouvelables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d15c7cb elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"d15c7cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_range&quot;:&quot;viewport&quot;,&quot;background_motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6021046 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"6021046\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d71475 elementor-widget elementor-widget-text-editor\" data-id=\"1d71475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>5<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adec4fa elementor-widget elementor-widget-text-editor\" data-id=\"adec4fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1e2e2b5\" data-id=\"1e2e2b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b51bdd3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b51bdd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c76af28\" data-id=\"c76af28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c88e7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"48c88e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"orange\">Port\u00e9e 3 :<\/span>\n\u00c9missions indirectes\nprovenant des\nfournisseurs mondiaux\nServices r\u00e9seau\net de la logistique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b6ea260\" data-id=\"b6ea260\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-42884b2\" data-id=\"42884b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-413c916 elementor-widget elementor-widget-text-editor\" data-id=\"413c916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9tant donn\u00e9 que Limos4 fournit principalement des services via son r\u00e9seau mondial de fournisseurs, la majorit\u00e9 des \u00e9missions et des d\u00e9chets rel\u00e8vent du Scope 3. Nous travaillons en \u00e9troite collaboration avec des fournisseurs de transport de confiance pour faire progresser les solutions de transport durables dans le monde entier. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26bd1b4 elementor-widget elementor-widget-text-editor\" data-id=\"26bd1b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Principales initiatives pour la r\u00e9duction du Scope 3 :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6d6936 e-con-full e-flex e-con e-parent\" data-id=\"b6d6936\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74dad30 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"74dad30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Achats \u00e9cologiques et engagement des fournisseurs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a64344c elementor-widget elementor-widget-text-editor\" data-id=\"a64344c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Partenariat avec des fournisseurs qui int\u00e8grent des v\u00e9hicules hybrides et \u00e9lectriques dans leurs flottes et mettent en \u0153uvre des pratiques soucieuses des d\u00e9chets dans l&#8217;entretien et la logistique des flottes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-091d33b e-con-full e-flex e-con e-parent\" data-id=\"091d33b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4825ab elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f4825ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Suivi des \u00e9missions de port\u00e9e 3<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5059175 elementor-widget elementor-widget-text-editor\" data-id=\"5059175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous proposons des rapports de durabilit\u00e9 d\u00e9taill\u00e9s et automatis\u00e9s qui permettent \u00e0 nos clients de suivre et de g\u00e9rer leur empreinte carbone li\u00e9e aux voyages.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4de4ae e-con-full e-flex e-con e-parent\" data-id=\"e4de4ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4ab45c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e4ab45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pratiques d\u2019\u00e9conomie circulaire<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1084f02 elementor-widget elementor-widget-text-editor\" data-id=\"1084f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Encourager les fournisseurs \u00e0 recycler les pi\u00e8ces, les fluides et les d\u00e9chets d\u2019emballage, r\u00e9duisant ainsi l\u2019impact sur les d\u00e9charges.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6af990 e-con-full e-flex e-con e-parent\" data-id=\"e6af990\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32b4333 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"32b4333\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Num\u00e9risation des op\u00e9rations<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-839836a elementor-widget elementor-widget-text-editor\" data-id=\"839836a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Minimiser les d\u00e9chets de bureau en passant \u00e0 la facturation sans papier, aux contrats \u00e9lectroniques et \u00e0 la gestion num\u00e9rique centralis\u00e9e des voyages.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06b2e69 e-con-full e-flex e-con e-parent\" data-id=\"06b2e69\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf198ac elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cf198ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gestion durable des d\u00e9chets informatiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf130ae elementor-widget elementor-widget-text-editor\" data-id=\"bf130ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Partenariat avec des recycleurs de d\u00e9chets \u00e9lectroniques pour \u00e9liminer de mani\u00e8re responsable les appareils \u00e9lectroniques obsol\u00e8tes et promouvoir la r\u00e9utilisation des \u00e9quipements informatiques de bureau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4c11b3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c4c11b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7c4f29 elementor-widget elementor-widget-text-editor\" data-id=\"c7c4f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Indicateurs cl\u00e9s du champ d&#8217;application 3<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-390c517 e-con-full e-flex e-con e-parent\" data-id=\"390c517\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a38179b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a38179b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9missions de GES par type de service<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2246577 elementor-widget elementor-widget-text-editor\" data-id=\"2246577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fournir des donn\u00e9es d&#8217;impact CO\u2082 pour tout type de service, par exemple les transferts a\u00e9roport, les voyages d&#8217;affaires et les transports \u00e9v\u00e9nementiels, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5de60d5 e-con-full e-flex e-con e-parent\" data-id=\"5de60d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a11522 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2a11522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comparaison de l'empreinte carbone des v\u00e9hicules<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c929557 elementor-widget elementor-widget-text-editor\" data-id=\"c929557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fournir aux clients des informations bas\u00e9es sur des donn\u00e9es concernant les \u00e9missions de diff\u00e9rentes cat\u00e9gories de v\u00e9hicules \u00e0 travers notre r\u00e9seau mondial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1ee630 e-con-full e-flex e-con e-parent\" data-id=\"d1ee630\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02d8b45 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"02d8b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Strat\u00e9gies de r\u00e9duction des \u00e9missions pour les clients<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2477fbe elementor-widget elementor-widget-text-editor\" data-id=\"2477fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aider les entreprises \u00e0 optimiser leurs programmes de voyage en s\u00e9lectionnant les options de v\u00e9hicules les plus durables disponibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8ed63d elementor-widget elementor-widget-text-editor\" data-id=\"e8ed63d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Initiative en cours :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d54eae4 elementor-widget elementor-widget-text-editor\" data-id=\"d54eae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9largir nos capacit\u00e9s de reporting sur la durabilit\u00e9 de port\u00e9e 3 en travaillant avec des fournisseurs qui s&#8217;alignent sur les exigences de conformit\u00e9 ESG de l&#8217;entreprise, garantissant ainsi que les clients re\u00e7oivent des donn\u00e9es d&#8217;\u00e9missions pr\u00e9cises et transparentes pour le suivi de la durabilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12f7aaa elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"12f7aaa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a47b9ea elementor-hidden-tablet elementor-hidden-phone\" data-id=\"a47b9ea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae85363 elementor-widget elementor-widget-text-editor\" data-id=\"ae85363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>6<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeaffbc elementor-widget elementor-widget-text-editor\" data-id=\"eeaffbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-70dc686\" data-id=\"70dc686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10a1a11 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"10a1a11\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-121764e\" data-id=\"121764e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4c4e1a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d4c4e1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mesurables\nEngagements :\nNeutralit\u00e9 carbone\nd'ici 2040<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1c1147b elementor-hidden-tablet elementor-hidden-phone\" data-id=\"1c1147b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4cc1f30\" data-id=\"4cc1f30\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7b143c elementor-widget elementor-widget-text-editor\" data-id=\"b7b143c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La durabilit\u00e9 dans les transports d&#8217;entreprise exige des actions mesurables, de la transparence et une responsabilit\u00e9 \u00e0 long terme. Atteindre la neutralit\u00e9 carbone d&#8217;ici 2040 \u2013 soit dix ans avant les objectifs de l&#8217;Accord de Paris \u2013 n\u00e9cessite une approche structur\u00e9e, fond\u00e9e sur les donn\u00e9es et couvrant l&#8217;ensemble de notre \u00e9cosyst\u00e8me op\u00e9rationnel. En signant l&#8217;Engagement Climat, Limos4 a clairement d\u00e9fini la voie \u00e0 suivre pour atteindre cet objectif. Cet engagement est concr\u00e9tis\u00e9 par une strat\u00e9gie globale align\u00e9e sur les principes fondamentaux de l&#8217;Engagement Climat :   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e95aa8c e-con-full e-flex e-con e-parent\" data-id=\"e95aa8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-990e169 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"990e169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rapports r\u00e9guliers<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1193eac elementor-widget elementor-widget-text-editor\" data-id=\"1193eac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une mesure pr\u00e9cise est essentielle \u00e0 une r\u00e9duction efficace des \u00e9missions de carbone. Limos4 suit et publie en continu ses \u00e9missions de gaz \u00e0 effet de serre (GES), garantissant ainsi la transparence et permettant des am\u00e9liorations continues. En fournissant des rapports de d\u00e9veloppement durable pr\u00e9cis et automatis\u00e9s, nous fournissons \u00e0 nos clients professionnels les donn\u00e9es dont ils ont besoin pour aligner leurs politiques de voyages sur les objectifs ESG.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4b666f e-con-full e-flex e-con e-parent\" data-id=\"f4b666f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7819653 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7819653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9limination du carbone<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc04ce8 elementor-widget elementor-widget-text-editor\" data-id=\"cc04ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9duction des \u00e9missions \u00e0 la source est essentielle \u00e0 la durabilit\u00e9 \u00e0 long terme. Limos4 met en \u0153uvre des initiatives de d\u00e9carbonation par : <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-119ba89 e-con-full e-flex e-con e-parent\" data-id=\"119ba89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e7b6aa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9e7b6aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9lectrification de la flotte :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b57a7 elementor-widget elementor-widget-text-editor\" data-id=\"b0b57a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9velopper l\u2019utilisation de v\u00e9hicules hybrides et \u00e9lectriques au sein de notre r\u00e9seau mondial de fournisseurs, en privil\u00e9giant les march\u00e9s dot\u00e9s de l\u2019infrastructure n\u00e9cessaire pour soutenir le transport durable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cae08b e-con-full e-flex e-con e-parent\" data-id=\"5cae08b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba0443e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ba0443e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Efficacit\u00e9 pilot\u00e9e par l'IA :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd43d3 elementor-widget elementor-widget-text-editor\" data-id=\"7cd43d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Optimiser la r\u00e9partition et l&#8217;acheminement gr\u00e2ce \u00e0 une technologie de pointe, minimiser la consommation de carburant et r\u00e9duire les \u00e9missions dans toutes les r\u00e9gions de service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7da73a e-con-full e-flex e-con e-parent\" data-id=\"a7da73a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41eebe1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"41eebe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Op\u00e9rations durables :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdce525 elementor-widget elementor-widget-text-editor\" data-id=\"cdce525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Am\u00e9liorer l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique des bureaux et des infrastructures num\u00e9riques pour r\u00e9duire les \u00e9missions indirectes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b4cb62 e-con-full e-flex e-con e-parent\" data-id=\"5b4cb62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce64b0e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ce64b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Compensations cr\u00e9dibles<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ff818 elementor-widget elementor-widget-text-editor\" data-id=\"53ff818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour rem\u00e9dier aux \u00e9missions r\u00e9siduelles, nous nous engageons \u00e0 les neutraliser par des compensations suppl\u00e9mentaires, quantifiables, r\u00e9elles, permanentes et socialement b\u00e9n\u00e9fiques, garantissant ainsi que notre objectif de z\u00e9ro \u00e9mission nette est \u00e0 la fois cr\u00e9dible et efficace.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e270871 elementor-widget elementor-widget-text-editor\" data-id=\"e270871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En adh\u00e9rant \u00e0 ces principes, Limos4 s&#8217;aligne non seulement sur les cadres mondiaux de durabilit\u00e9, mais d\u00e9montre \u00e9galement une forte concentration sur les voyages responsables, garantissant \u00e0 nos clients de b\u00e9n\u00e9ficier de solutions respectueuses de l&#8217;environnement sans compromettre l&#8217;excellence du service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d2abb9 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"8d2abb9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_range&quot;:&quot;viewport&quot;,&quot;background_motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f2acd5c elementor-hidden-tablet elementor-hidden-phone\" data-id=\"f2acd5c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bcbdc4 elementor-widget elementor-widget-text-editor\" data-id=\"5bcbdc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>7<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58bcc5e elementor-widget elementor-widget-text-editor\" data-id=\"58bcc5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1b9dd43\" data-id=\"1b9dd43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dec78f3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dec78f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4c409f1\" data-id=\"4c409f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-093b4d3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"093b4d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transparence et mise en \u0153uvre\nD\u00e9veloppement durable\nRapports<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e250cd4\" data-id=\"e250cd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-80f538d\" data-id=\"80f538d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-977f69e elementor-widget elementor-widget-text-editor\" data-id=\"977f69e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les rapports de d\u00e9veloppement durable de Limos4 sont con\u00e7us pour fournir aux responsables des voyages d&#8217;affaires, aux \u00e9quipes achats et aux responsables ESG des donn\u00e9es pr\u00e9cises et exploitables pour soutenir leurs engagements en mati\u00e8re de d\u00e9veloppement durable et leurs efforts de conformit\u00e9. Ces rapports se distinguent par leur profondeur, leur accessibilit\u00e9 et leur personnalisation, permettant aux entreprises d&#8217;int\u00e9grer facilement le suivi des \u00e9missions \u00e0 leur strat\u00e9gie environnementale globale. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c6e2f4 e-con-full e-flex e-con e-parent\" data-id=\"4c6e2f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e596b5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9e596b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Int\u00e9gr\u00e9 aux principaux points de contact des rapports<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a503a4e elementor-widget elementor-widget-text-editor\" data-id=\"a503a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les informations sur les \u00e9missions sont automatiquement incluses dans les confirmations de r\u00e9servation, les rapports de service finaux et d\u2019autres enregistrements de voyage pertinents, offrant une visibilit\u00e9 instantan\u00e9e sur l\u2019empreinte carbone de chaque trajet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bde5e0 e-con-full e-flex e-con e-parent\" data-id=\"3bde5e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aebd186 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"aebd186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enti\u00e8rement personnalisable pour l'analyse strat\u00e9gique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb19f0d elementor-widget elementor-widget-text-editor\" data-id=\"fb19f0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les rapports peuvent \u00eatre g\u00e9n\u00e9r\u00e9s via le portail Limos4, avec des options de filtrage bas\u00e9es sur le r\u00e9servataire, le centre de co\u00fbts, le voyageur, la p\u00e9riode, etc., permettant aux entreprises de suivre les performances de durabilit\u00e9 \u00e0 plusieurs niveaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8610f9a e-con-full e-flex e-con e-parent\" data-id=\"8610f9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3002d89 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3002d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flexibilit\u00e9 \u00e0 la demande<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72657b8 elementor-widget elementor-widget-text-editor\" data-id=\"72657b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des rapports personnalis\u00e9s suppl\u00e9mentaires sont disponibles sur demande aupr\u00e8s de notre \u00e9quipe de service client d\u00e9di\u00e9e, garantissant ainsi aux entreprises l&#8217;acc\u00e8s \u00e0 des donn\u00e9es compl\u00e8tes et pr\u00eates \u00e0 \u00eatre audit\u00e9es en cas de besoin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a16ccd e-con-full e-flex e-con e-parent\" data-id=\"2a16ccd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6bb577 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e6bb577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soutient les objectifs ESG et de conformit\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c8655 elementor-widget elementor-widget-text-editor\" data-id=\"63c8655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En proposant des mesures de durabilit\u00e9 transparentes et tra\u00e7ables, ces rapports permettent aux organisations d&#8217;atteindre leurs objectifs de durabilit\u00e9, d&#8217;am\u00e9liorer les rapports ESG et de mettre en \u0153uvre des politiques de voyage plus responsables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ed5cc elementor-widget elementor-widget-text-editor\" data-id=\"e6ed5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En int\u00e9grant la durabilit\u00e9 \u00e0 chaque voyage, Limos4 permet aux entreprises de transformer les donn\u00e9es de voyage en actions environnementales significatives, garantissant un transport d&#8217;entreprise responsable sans compromettre l&#8217;efficacit\u00e9 ou l&#8217;excellence du service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c59797c elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"c59797c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4e07142 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"4e07142\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ea6c9 elementor-widget elementor-widget-text-editor\" data-id=\"c5ea6c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>8<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50978bb elementor-widget elementor-widget-text-editor\" data-id=\"50978bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p> <\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c7dda0a\" data-id=\"c7dda0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c4744ea elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c4744ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-422f3c8\" data-id=\"422f3c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c672dd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6c672dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reboisement de Limos4\nInitiative : Restaurer\nL'\u00e9quilibre au-del\u00e0\nTransport<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1e34f66 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"1e34f66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-64d1b62\" data-id=\"64d1b62\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a4fe6c elementor-widget elementor-widget-text-editor\" data-id=\"1a4fe6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La durabilit\u00e9 ne se limite pas \u00e0 la r\u00e9duction des \u00e9missions : elle n\u00e9cessite un investissement actif dans la restauration environnementale. Limos4 participe activement \u00e0 la restauration \u00e9cologique gr\u00e2ce \u00e0 son initiative de reboisement, contribuant ainsi \u00e0 la s\u00e9questration du carbone \u00e0 long terme, \u00e0 l&#8217;am\u00e9lioration de la biodiversit\u00e9 et \u00e0 la pr\u00e9servation des \u00e9cosyst\u00e8mes. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4937c4 elementor-widget elementor-widget-text-editor\" data-id=\"b4937c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans le cadre de cette initiative, nous avons plant\u00e9 les 100 premiers ch\u00eanes, consolidant ainsi notre engagement pour un avenir plus vert, au-del\u00e0 de la durabilit\u00e9 op\u00e9rationnelle. Les ch\u00eanes, reconnus pour leur exceptionnelle capacit\u00e9 d&#8217;absorption du carbone et leur long\u00e9vit\u00e9, constituent un investissement environnemental durable, soutenant les \u00e9cosyst\u00e8mes et am\u00e9liorant la qualit\u00e9 de l&#8217;air. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5555aec elementor-widget elementor-widget-text-editor\" data-id=\"5555aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette initiative compl\u00e8te notre strat\u00e9gie globale de d\u00e9veloppement durable, garantissant que l&#8217;engagement de Limos4 en faveur d&#8217;un voyage responsable va au-del\u00e0 du transport lui-m\u00eame. En int\u00e9grant des actions environnementales concr\u00e8tes \u00e0 des solutions de transport durables et avant-gardistes, nous relevons le niveau de responsabilit\u00e9 d&#8217;entreprise dans le secteur du transport terrestre. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ab156b elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"6ab156b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_range&quot;:&quot;viewport&quot;,&quot;background_motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5c510b8 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"5c510b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3c539 elementor-widget elementor-widget-text-editor\" data-id=\"fb3c539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>9<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfdb8cd elementor-widget elementor-widget-text-editor\" data-id=\"cfdb8cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-605ba4a\" data-id=\"605ba4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43d705d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"43d705d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f5ae21\" data-id=\"2f5ae21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fae460 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6fae460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Innovation num\u00e9rique\npour des op\u00e9rations\ndurables<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4da3561\" data-id=\"4da3561\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1077ac6\" data-id=\"1077ac6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52aaba1 elementor-widget elementor-widget-text-editor\" data-id=\"52aaba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La durabilit\u00e9 dans le transport terrestre ne se limite pas \u00e0 la r\u00e9duction des \u00e9missions des v\u00e9hicules. Limos4 int\u00e8gre des solutions num\u00e9riques avanc\u00e9es et des strat\u00e9gies op\u00e9rationnelles intelligentes pour minimiser les d\u00e9chets, am\u00e9liorer l&#8217;efficacit\u00e9 et s&#8217;aligner sur les objectifs de d\u00e9veloppement durable de l&#8217;entreprise. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a533170 elementor-widget elementor-widget-text-editor\" data-id=\"a533170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gr\u00e2ce \u00e0 des technologies de pointe et \u00e0 l&#8217;automatisation des processus, nous r\u00e9duisons consid\u00e9rablement le gaspillage de papier, les inefficacit\u00e9s administratives et la consommation de ressources, sans compromettre l&#8217;exp\u00e9rience client. Parmi nos principales initiatives, citons : <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95a9a3a e-con-full e-flex e-con e-parent\" data-id=\"95a9a3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fde717 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7fde717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optimisation de la r\u00e9servation et de la r\u00e9partition en temps r\u00e9el gr\u00e2ce \u00e0 l'IA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8be8c8c elementor-widget elementor-widget-text-editor\" data-id=\"8be8c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le routage intelligent et l&#8217;affectation des chauffeurs maximisent l&#8217;efficacit\u00e9 de la flotte, r\u00e9duisant ainsi la consommation de carburant et l&#8217;utilisation inutile des v\u00e9hicules.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0f5dc0 e-con-full e-flex e-con e-parent\" data-id=\"f0f5dc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58c0fc4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"58c0fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rapports automatis\u00e9s sur les \u00e9missions<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-457db1d elementor-widget elementor-widget-text-editor\" data-id=\"457db1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les informations sur les \u00e9missions sont fournies num\u00e9riquement, permettant aux entreprises clientes de suivre et d\u2019\u00e9valuer facilement leur empreinte carbone li\u00e9e aux d\u00e9placements.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a024f17 e-con-full e-flex e-con e-parent\" data-id=\"a024f17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ecb92f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9ecb92f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Portail client pour la gestion centralis\u00e9e<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-813dab7 elementor-widget elementor-widget-text-editor\" data-id=\"813dab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une plateforme enti\u00e8rement num\u00e9rique rationalise la planification, le suivi et la cr\u00e9ation de rapports de voyage, \u00e9liminant ainsi les confirmations, les itin\u00e9raires et les factures sur papier.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43a7e0b e-con-full e-flex e-con e-parent\" data-id=\"43a7e0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5fb17 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f5fb17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-fiber_manual_record\" data-md-icon=\"fiber_manual_record\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transactions et documentation sans papier<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-653b1cb elementor-widget elementor-widget-text-editor\" data-id=\"653b1cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La facturation \u00e9lectronique et la tenue de registres num\u00e9riques minimisent l\u2019impact environnemental tout en am\u00e9liorant l\u2019efficacit\u00e9 et la s\u00e9curit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bba6734 elementor-widget elementor-widget-text-editor\" data-id=\"bba6734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ces gains d&#8217;efficacit\u00e9 technologiques contribuent \u00e0 r\u00e9duire l&#8217;empreinte environnementale tout en am\u00e9liorant la commodit\u00e9, la pr\u00e9cision et la transparence pour nos clients. Chez Limos4, la transformation num\u00e9rique est un pilier essentiel du d\u00e9veloppement durable, garantissant que nos op\u00e9rations restent responsables et tourn\u00e9es vers l&#8217;avenir dans un contexte \u00e9conomique en constante \u00e9volution. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca34a7b elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"ca34a7b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-40e4211 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"40e4211\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8879ba0 elementor-widget elementor-widget-text-editor\" data-id=\"8879ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae5feec elementor-widget elementor-widget-text-editor\" data-id=\"ae5feec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p> <\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p><p>|<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0925ae5\" data-id=\"0925ae5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40df95c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40df95c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8352dd9\" data-id=\"8352dd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4affd91 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4affd91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un avenir plus vert\nDemain commence\nAujourd'hui<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2de5b9c elementor-hidden-tablet elementor-hidden-phone\" data-id=\"2de5b9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-43d9da4\" data-id=\"43d9da4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b579ca elementor-widget elementor-widget-text-editor\" data-id=\"3b579ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Limos4 transforme le d\u00e9veloppement durable, autrefois une obligation, en un avantage concurrentiel. Chaque choix de v\u00e9hicule, chaque itin\u00e9raire et chaque donn\u00e9e sont optimis\u00e9s pour r\u00e9duire les \u00e9missions sans compromettre l&#8217;efficacit\u00e9. L&#8217;expansion de la flotte hybride et \u00e9lectrique, la gestion des d\u00e9placements bas\u00e9e sur l&#8217;IA et le suivi pr\u00e9cis des \u00e9missions carbone garantissent que les transports d&#8217;entreprise s&#8217;alignent sur les objectifs environnementaux concrets.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7ab108 elementor-widget elementor-widget-text-editor\" data-id=\"e7ab108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;engagement de neutralit\u00e9 carbone d&#8217;ici 2040 s&#8217;inscrit dans une strat\u00e9gie structur\u00e9e et mesurable, s&#8217;appuyant sur la transparence et l&#8217;innovation. En int\u00e9grant des pratiques responsables \u00e0 tous les niveaux, Limos4 offre aux entreprises la certitude que chaque kilom\u00e8tre parcouru les fait progresser, de mani\u00e8re intelligente, responsable et sans compromis. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1 | | | | | | | | | | | | | | | | D\u00e9veloppement durable chez Limos4 : Conduire l&#8217;avenirDe mani\u00e8re responsable Une approche plus \u00e9cologique du transport terrestre Chez Limos4, [&hellip;]<\/p>\n","protected":false},"author":597,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"wf_page_folders":[10],"class_list":["post-94237","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Durabilit\u00e9 - Limos4<\/title>\n<meta name=\"description\" content=\"Chez Limos4, le d\u00e9veloppement durable est un \u00e9l\u00e9ment fondamental de notre vision de l&#039;avenir du transport terrestre. Nous am\u00e9liorons continuellement nos op\u00e9rations afin de r\u00e9duire les \u00e9missions, d&#039;optimiser l&#039;efficacit\u00e9 et de renforcer la durabilit\u00e9 du transport terrestre avec chauffeur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.limos4.com\/fr\/durabilite\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Durabilit\u00e9 - Limos4\" \/>\n<meta property=\"og:description\" content=\"Limos4 - Premium Worldwide Chauffeured Limousine Service. Limos4 - Premium Airport and Cruise Port Transfers. English speaking drivers. No Hidden Costs. Meet and Greet. Comfort &amp; VIP. 24\/7 Customer Support. Experienced Chauffeurs. Reliable &amp; Safe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.limos4.com\/fr\/durabilite\" \/>\n<meta property=\"og:site_name\" content=\"Limos4\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/limos4\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T06:20:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/08\/limos4-seo-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@limos4net\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite\",\"url\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite\",\"name\":\"Durabilit\u00e9 - Limos4\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.limos4.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/list.png\",\"datePublished\":\"2025-07-14T10:39:29+00:00\",\"dateModified\":\"2026-07-06T06:20:52+00:00\",\"description\":\"Chez Limos4, le d\u00e9veloppement durable est un \u00e9l\u00e9ment fondamental de notre vision de l'avenir du transport terrestre. Nous am\u00e9liorons continuellement nos op\u00e9rations afin de r\u00e9duire les \u00e9missions, d'optimiser l'efficacit\u00e9 et de renforcer la durabilit\u00e9 du transport terrestre avec chauffeur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite#primaryimage\",\"url\":\"https:\\\/\\\/www.limos4.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/list.png\",\"contentUrl\":\"https:\\\/\\\/www.limos4.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/list.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/durabilite#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.limos4.com\\\/fr\\\/page-daccueil\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Durabilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#website\",\"url\":\"https:\\\/\\\/www.limos4.com\\\/fr\",\"name\":\"Limos4\",\"description\":\"Worldwide Chauffeured Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.limos4.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#organization\",\"name\":\"Limos4 GmbH\",\"url\":\"https:\\\/\\\/www.limos4.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.limos4.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/l4_logo-e1682058966339.png\",\"contentUrl\":\"https:\\\/\\\/www.limos4.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/l4_logo-e1682058966339.png\",\"width\":360,\"height\":361,\"caption\":\"Limos4 GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.limos4.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/limos4\\\/\",\"https:\\\/\\\/x.com\\\/limos4net\",\"https:\\\/\\\/www.instagram.com\\\/limos4_net\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/limos4\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Limos4Net\"],\"description\":\"Our carefully selected team of professionals has a wealth of experience and skills to provide you with an unparalleled service all down the line. Supported by our cutting-edge technological facilities, we are ready to assist you with all your chauffeured transportation requirements in the most efficient and streamlined way. Every staff member is highly enthusiastic about serving you, striving for total customer satisfaction.\",\"email\":\"info@limos4.com\",\"telephone\":\"+41 43 505 24 24\",\"legalName\":\"Limos4 GmbH\",\"foundingDate\":\"2010-09-20\",\"vatID\":\"48-024-0788\",\"duns\":\"48-024-0788\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Durabilit\u00e9 - Limos4","description":"Chez Limos4, le d\u00e9veloppement durable est un \u00e9l\u00e9ment fondamental de notre vision de l'avenir du transport terrestre. Nous am\u00e9liorons continuellement nos op\u00e9rations afin de r\u00e9duire les \u00e9missions, d'optimiser l'efficacit\u00e9 et de renforcer la durabilit\u00e9 du transport terrestre avec chauffeur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.limos4.com\/fr\/durabilite","og_locale":"fr_FR","og_type":"article","og_title":"Durabilit\u00e9 - Limos4","og_description":"Limos4 - Premium Worldwide Chauffeured Limousine Service. Limos4 - Premium Airport and Cruise Port Transfers. English speaking drivers. No Hidden Costs. Meet and Greet. Comfort & VIP. 24\/7 Customer Support. Experienced Chauffeurs. Reliable & Safe.","og_url":"https:\/\/www.limos4.com\/fr\/durabilite","og_site_name":"Limos4","article_publisher":"https:\/\/www.facebook.com\/limos4\/","article_modified_time":"2026-07-06T06:20:52+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/www.limos4.com\/wp-content\/uploads\/2021\/08\/limos4-seo-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@limos4net","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.limos4.com\/fr\/durabilite","url":"https:\/\/www.limos4.com\/fr\/durabilite","name":"Durabilit\u00e9 - Limos4","isPartOf":{"@id":"https:\/\/www.limos4.com\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/www.limos4.com\/fr\/durabilite#primaryimage"},"image":{"@id":"https:\/\/www.limos4.com\/fr\/durabilite#primaryimage"},"thumbnailUrl":"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/07\/list.png","datePublished":"2025-07-14T10:39:29+00:00","dateModified":"2026-07-06T06:20:52+00:00","description":"Chez Limos4, le d\u00e9veloppement durable est un \u00e9l\u00e9ment fondamental de notre vision de l'avenir du transport terrestre. Nous am\u00e9liorons continuellement nos op\u00e9rations afin de r\u00e9duire les \u00e9missions, d'optimiser l'efficacit\u00e9 et de renforcer la durabilit\u00e9 du transport terrestre avec chauffeur.","breadcrumb":{"@id":"https:\/\/www.limos4.com\/fr\/durabilite#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.limos4.com\/fr\/durabilite"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.limos4.com\/fr\/durabilite#primaryimage","url":"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/07\/list.png","contentUrl":"https:\/\/www.limos4.com\/wp-content\/uploads\/2025\/07\/list.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.limos4.com\/fr\/durabilite#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.limos4.com\/fr\/page-daccueil"},{"@type":"ListItem","position":2,"name":"Durabilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.limos4.com\/fr#website","url":"https:\/\/www.limos4.com\/fr","name":"Limos4","description":"Worldwide Chauffeured Service","publisher":{"@id":"https:\/\/www.limos4.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.limos4.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.limos4.com\/fr#organization","name":"Limos4 GmbH","url":"https:\/\/www.limos4.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.limos4.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/04\/l4_logo-e1682058966339.png","contentUrl":"https:\/\/www.limos4.com\/wp-content\/uploads\/2023\/04\/l4_logo-e1682058966339.png","width":360,"height":361,"caption":"Limos4 GmbH"},"image":{"@id":"https:\/\/www.limos4.com\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/limos4\/","https:\/\/x.com\/limos4net","https:\/\/www.instagram.com\/limos4_net\/","https:\/\/www.linkedin.com\/company\/limos4","https:\/\/www.youtube.com\/c\/Limos4Net"],"description":"Our carefully selected team of professionals has a wealth of experience and skills to provide you with an unparalleled service all down the line. Supported by our cutting-edge technological facilities, we are ready to assist you with all your chauffeured transportation requirements in the most efficient and streamlined way. Every staff member is highly enthusiastic about serving you, striving for total customer satisfaction.","email":"info@limos4.com","telephone":"+41 43 505 24 24","legalName":"Limos4 GmbH","foundingDate":"2010-09-20","vatID":"48-024-0788","duns":"48-024-0788","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/pages\/94237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/users\/597"}],"replies":[{"embeddable":true,"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/comments?post=94237"}],"version-history":[{"count":8,"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/pages\/94237\/revisions"}],"predecessor-version":[{"id":97419,"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/pages\/94237\/revisions\/97419"}],"wp:attachment":[{"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/media?parent=94237"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.limos4.com\/fr\/wp-json\/wp\/v2\/wf_page_folders?post=94237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}